{"id":7073,"date":"2023-05-23T10:45:21","date_gmt":"2023-05-23T03:45:21","guid":{"rendered":"https:\/\/inmu.mahidol.ac.th\/th\/?p=7073"},"modified":"2024-02-21T10:47:16","modified_gmt":"2024-02-21T03:47:16","slug":"%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a0%e0%b8%8a%e0%b8%99%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a1-%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-%e0%b8%99","status":"publish","type":"post","link":"https:\/\/inmu.mahidol.ac.th\/th\/7073\/","title":{"rendered":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e19\u0e33\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e08\u0e32\u0e01\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e25\u0e32\u0e27 \u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e28\u0e32\u0e25\u0e32\u0e22\u0e32"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7073\" class=\"elementor elementor-7073\">\n\t\t\t\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-b0384bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0384bd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ae0342\" data-id=\"4ae0342\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77f9b6a elementor-widget elementor-widget-image\" data-id=\"77f9b6a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.0 - 09-01-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/inmu.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/05\/240566-5-768x512-1.jpg\" class=\"attachment-large size-large wp-image-7075\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/inmu.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/05\/240566-5-768x512-1.jpg 768w, https:\/\/inmu.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/05\/240566-5-768x512-1-300x200.jpg 300w, https:\/\/inmu.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/05\/240566-5-768x512-1-272x182.jpg 272w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-af71397 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af71397\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7796753\" data-id=\"7796753\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73be960 elementor-widget elementor-widget-text-editor\" data-id=\"73be960\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.0 - 09-01-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<span style=\"color: #000000;\">\u00a0 \u00a0 \u00a0 \u00a0 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 23 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2566 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e19\u0e33\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e08\u0e32\u0e01\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e25\u0e32\u0e27 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e28\u0e32\u0e25\u0e32\u0e22\u0e32<\/span>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-6d205de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d205de\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-467e891\" data-id=\"467e891\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c57be7 elementor-widget elementor-widget-image\" data-id=\"8c57be7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/inmu.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/05\/240566-4-768x512-1.jpg\" class=\"attachment-large size-large wp-image-7076\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/inmu.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/05\/240566-4-768x512-1.jpg 768w, https:\/\/inmu.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/05\/240566-4-768x512-1-300x200.jpg 300w, https:\/\/inmu.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/05\/240566-4-768x512-1-272x182.jpg 272w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-af0f696\" data-id=\"af0f696\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2af2caf elementor-widget elementor-widget-image\" data-id=\"2af2caf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/inmu.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/05\/240566-1-768x512-1.jpg\" class=\"attachment-large size-large wp-image-7077\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/inmu.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/05\/240566-1-768x512-1.jpg 768w, https:\/\/inmu.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/05\/240566-1-768x512-1-300x200.jpg 300w, https:\/\/inmu.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/05\/240566-1-768x512-1-272x182.jpg 272w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 23 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2566 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e19\u0e33\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e08\u0e32\u0e01\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e25\u0e32\u0e27 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e28\u0e32\u0e25\u0e32\u0e22\u0e32<\/p>\n","protected":false},"author":1,"featured_media":7075,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,3],"tags":[],"_links":{"self":[{"href":"https:\/\/inmu.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts\/7073"}],"collection":[{"href":"https:\/\/inmu.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inmu.mahidol.ac.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inmu.mahidol.ac.th\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/inmu.mahidol.ac.th\/th\/wp-json\/wp\/v2\/comments?post=7073"}],"version-history":[{"count":4,"href":"https:\/\/inmu.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts\/7073\/revisions"}],"predecessor-version":[{"id":7080,"href":"https:\/\/inmu.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts\/7073\/revisions\/7080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmu.mahidol.ac.th\/th\/wp-json\/wp\/v2\/media\/7075"}],"wp:attachment":[{"href":"https:\/\/inmu.mahidol.ac.th\/th\/wp-json\/wp\/v2\/media?parent=7073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inmu.mahidol.ac.th\/th\/wp-json\/wp\/v2\/categories?post=7073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inmu.mahidol.ac.th\/th\/wp-json\/wp\/v2\/tags?post=7073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}